{"id":5416,"date":"2025-06-06T12:00:00","date_gmt":"2025-06-06T10:00:00","guid":{"rendered":"http:\/\/historikerkraus.de\/blog\/?p=5416"},"modified":"2025-06-04T19:20:33","modified_gmt":"2025-06-04T17:20:33","slug":"tv-vorschau-7-13-juni-2025","status":"publish","type":"post","link":"http:\/\/historikerkraus.de\/blog\/2025\/06\/06\/tv-vorschau-7-13-juni-2025\/","title":{"rendered":"TV-Vorschau 7. \u2013 13. Juni 2025"},"content":{"rendered":"\n<p>Viel Spa\u00df bei der Auswahl der Geschichtssendungen!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"samstag7.juni\">Samstag, 7. Juni<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u201eDie Spaltung der Welt \u00b7 1939\u20131962\u201c findet ihren Abschluss. Um 20.15 Uhr steht <a href=\"https:\/\/www.br.de\/fernsehen\/ard-alpha\/programmkalender\/ausstrahlung-3838604.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eHeiliges Land\u201c<\/a> im Mittelpunkt. \u2014Am Ende beginnt <a href=\"https:\/\/www.br.de\/fernsehen\/ard-alpha\/programmkalender\/ausstrahlung-3838606.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eEine neue \u00c4ra\u201c<\/a> (21.05 Uhr). Alles auf <strong>ard-alpha<\/strong>.<\/li>\n\n\n\n<li>Religion und Architektur stehen bei <strong>Arte<\/strong> auf dem Programm. <a href=\"https:\/\/www.arte.tv\/de\/videos\/122690-000-A\/das-grabtuch-von-turin-ein-mysterium\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eDas Grabtuch von Turin, ein Mysterium\u201c<\/a> erwartet uns um 20.15 Uhr. <em>\u201eDie Dokumentation \u00fcber das Turiner Grabtuch ist als kriminalistische Spurensuche angelegt, von der Grabeskirche in Jerusalem bis in die Unterwelt von Istanbul, wo das Grabtuch \u2013 der Legende nach \u2013 lange Zeit verborgen war. Im franz\u00f6sischen Lirey wurde es 1354 nach Christus \u2013 historisch bezeugt \u2013 erstmals ausgestellt. Und seit gut 300 Jahren wird es in Turin \u2013 in einer eigens errichteten Kapelle \u2013 aufbewahrt; ergriffen verehrt von den einen, kritisch be\u00e4ugt von den anderen.\u201c<\/em> \u2014 <em>\u201eMit der Ausbreitung des Christentums ging die Entstehung von religi\u00f6sen St\u00e4tten einher, in denen der Glaube praktiziert werden konnte: Kl\u00f6ster und Kirchen wurden errichtet und schlie\u00dflich immer h\u00f6here und gr\u00f6\u00dfere Kathedralen.\u201c<\/em> <a href=\"https:\/\/www.arte.tv\/de\/videos\/048554-001-A\/sakrale-bauwerke\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eSakrale Bauwerke \u2013 Vom Streben nach H\u00f6he und Licht: Kirchen\u201c<\/a>, 21.45 Uhr. \u2014 Der <a href=\"https:\/\/www.arte.tv\/de\/videos\/095807\u2013002-A\/aachener-dom\/\" target=\"_blank\" rel=\"noopener\" title=\"\">\u201eAachener Dom \u2013 Unesco-Welterbe und steingewordene Geschichte\u201c<\/a> ist Thema um 23.15 Uhr. <em>\u201eEr ist der Symbolbau einer neuen Epoche: der Aachener Dom. Im Jahr 798 als Kapelle der Kaiserpfalz geweiht, wollte Karl der Gro\u00dfe mit diesem Kirchenbau ein Abbild des Himmels auf Erden schaffen. Der Aachener Dom \u00fcberstand mehrere Kriege und Stadtbr\u00e4nde. Mit seiner au\u00dfergew\u00f6hnlichen karolingischen Architektur ist und bleibt der Dom ein Monument der Ewigkeit.\u201c<\/em><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"sonntag8.junipfingsten\">Sonntag, 8. Juni \u2013 Pfingsten<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.ndr.de\/fernsehen\/programm\/epg\/Die-Manns-Ein-Jahrhundertroman,sendung1543696.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eDie Manns \u2013 Ein Jahrhundertroman (Teil 2): 1933\u20131941\u201c<\/a> (BRD 2001, Regie: Heinrich Breloer), erz\u00e4hlt die Geschichte der ber\u00fchmten Schriftstellerfamilie fort (<strong>ndr<\/strong>, 23.30 Uhr).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"montag9.junipfingstmontag\">Montag, 9. Juni \u2013 Pfingstmontag<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Der dritte und letzte Teil des Films <a href=\"https:\/\/www.ndr.de\/fernsehen\/programm\/epg\/Die-Manns-Ein-Jahrhundertroman,sendung1543706.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eDie Manns \u2013 Ein Jahrhundertroman\u201c<\/a> (BRD 2001, Regie: Heinrich Breloer) ist im <strong>ndr<\/strong> um 22.55 Uhr zu sehen.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"dienstag10.juni\">Dienstag, 10. Juni<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>\u201eZwischen 1930 und 1945 erlebte Osteuropa Massengewalt beispiellosen Ausma\u00dfes. Hitler und Stalin benutzten die riesige Region f\u00fcr ihre jeweiligen Expansionspl\u00e4ne. Sch\u00e4tzungen zufolge wurden etwa 14 Millionen Zivilist<\/em>innen ermordet \u2013 vor allem Juden, Polen, Balten, Belarussen und Ukrainer.\u201c* <a href=\"https:\/\/www.arte.tv\/de\/videos\/118249-000-A\/osteuropa-zwischen-hitler-und-stalin-das-grosse-sterben\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eOsteuropa zwischen Hitler und Stalin \u2013 Das gro\u00dfe Sterben\u201c<\/a>, <strong>Arte<\/strong>, 20.15 Uhr. \u2014 Der Film <a href=\"https:\/\/www.arte.tv\/de\/videos\/118257-000-A\/terror-und-champagner-hitlers-stellvertreter-in-paris\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eTerror und Champagner \u2013 Hitlers Stellvertreter in Paris\u201c<\/a> folgt um 21.50 Uhr. \u2014 <em>\u201eSommer, 1944: Deutsche Soldaten k\u00e4mpfen in Italien. Immer weniger von ihnen glauben noch daran, dass Deutschland den Zweiten Weltkrieg gewinnen kann. Einige laufen zu den italienischen Partisanen \u00fcber. Rund 80 Jahre sp\u00e4ter gehen drei Nachfahren in Italien auf Spurensuche.\u201c<\/em> <a href=\"https:\/\/www.arte.tv\/de\/videos\/116019-000-A\/bella-ciao-vom-deutschen-soldaten-zum-partisan\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eBella Ciao! \u2013 Vom deutschen Soldaten zum Partisan\u201c<\/a> (22.40 Uhr). \u2014 Geschichten aus dem Kalten Krieg <a href=\"https:\/\/www.arte.tv\/de\/videos\/111688-000-A\/geheimauftrag-moskau-wie-aktivistinnen-russischen-juden-halfen\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eGeheimauftrag Moskau: Wie Aktivistinnen russischen Juden halfen\u201c<\/a> (23.35 Uhr). <em>\u201eGeheimauftrag Moskau: Das Frauen-Netzwerk \u201aThe 35s\u2018 wurde Anfang der 1970er Jahre mitten im Kalten Krieg von j\u00fcdischen Hausfrauen und M\u00fcttern in London gegr\u00fcndet. Von Protestaktionen und Demos bis hin zu geheimen Missionen hinter dem Eisernen Vorhang k\u00e4mpften diese Frauen, getarnt als Touristinnen, f\u00fcr die Rechte und Freiheiten der unterdr\u00fcckten sowjetischen Juden.\u201c<\/em><\/li>\n\n\n\n<li><strong>3sat<\/strong> sendet um 22.25 Uhr den Beitrag <a href=\"https:\/\/www.ardmediathek.de\/video\/dokus-und-reportagen\/verraeterkinder-die-toechter-und-soehne-des-widerstands\/hr\/MWVkMzlmYWMtNzE1Yi00ZTIzLWFlOWMtMGZhODkzMjQ3Yjg2\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eVerr\u00e4terkinder \u2013 Die T\u00f6chter und S\u00f6hne des Widerstands\u201c<\/a>. <em>\u201eDie M\u00e4nner des 20. Juli 1944 werden heute verehrt als Helden, die ihr Leben im Widerstand gegen Hitler geopfert haben. F\u00fcr ihre Kinder ist der gewaltsame Tod des Vaters eine Katastrophe, an deren Folgen sie bis in die Gegenwart zu tragen haben.\u201c<\/em> \u2014 Um 23.10 Uhr folgt die Doku <a href=\"https:\/\/www.3sat.de\/dokumentation\/geschichte\/die-wittelsbacher-geiseln-adolf-hitlers-102.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eDie Wittelsbacher \u2013 Geiseln Adolf Hitlers\u201c<\/a>. <em>\u201eDie Zeit des \u201eDritten Reichs\u201c war auch f\u00fcr die Wittelsbacher eine Zeit des Leidens. Die Nationalsozialisten f\u00fcrchteten eine Thronbesteigung des bayerischen Kronprinzen Rupprecht. Der Sohn des letzten bayerischen K\u00f6nigs fl\u00fcchtete ins Exil, seine Familie wurde von den Nazis verfolgt. Die einzelnen Familienangeh\u00f6rigen der Wittelsbacher wurden in die Konzentrationslager Sachsenhausen, Flossenb\u00fcrg und Dachau verschleppt.\u201c<\/em><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"mittwoch11.juni\">Mittwoch, 11. Juni<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Heute eine Fehlanzeige.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"donnerstag12.juni\">Donnerstag, 12. Juni<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Der Geschichtsabend auf <a href=\"https:\/\/www.n-tv.de\/mediathek\/tvprogramm\/?date=2025-06-12\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>n-tv<\/strong><\/a> enth\u00e4lt u.a. eine Doku zum Thema \u201eWettlauf um die Atombombe \u2013 Hitler und die Alliierten\u201c bereit (22.05 Uhr).<\/li>\n\n\n\n<li>Der <strong>hr<\/strong> erinnert um 23 Uhr an <a href=\"https:\/\/www.ardmediathek.de\/video\/ard-history\/emilie-schindler-die-vergessene-heldin\/br\/Y3JpZDovL2JyLmRlL2Jyb2FkY2FzdC9kMTgzNDdjZC0yNjQ0LTQ3MTgtYTEwZi0zYTdkNWQ3OWYxZmZfb25saW5lYnJvYWRjYXN0\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eEmilie Schindler \u00b7 Die vergessene Heldin\u201c<\/a>. <em>\u201eEmilie Schindler, die als betrogene Ehefrau von vielen bel\u00e4chelt wurde, ist eine von der Geschichte vergessene Heldin, die furchtlos und mutig Juden rettete. Die Dokumentation holt sie aus dem Schatten ihres Mannes.\u201c<\/em> \u2014 Um 23.45 Uhr folgt die Doku <a href=\"https:\/\/www.ardmediathek.de\/sendung\/die-ungewollten-die-irrfahrt-der-st-louis\/Y3JpZDovL25kci5kZS80ODc4IGNyaWQ6Ly9uZHIuZGUvcHJvcGxhbl8xOTYyNzQ0NjVfZ2FuemVTZW5kdW5n\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eDie Ungewollten \u2013 Die Irrfahrt der St. Louis\u201c<\/a>. <em>\u201eVoller Zuversicht verlassen 937 j\u00fcdische Fl\u00fcchtlinge 1939 den Hamburger Hafen. Nazideutschland hinter sich, die Freiheit vor sich. Ein Visum f\u00fcr Kuba verspricht ein Leben ohne Angst. Doch Havanna verweigert die Einreise. Kapit\u00e4n Schr\u00f6der nimmt Kurs auf die USA. Auch Washington l\u00e4sst die \u201cSt. Louis\u201d nicht in einen sicheren Hafen. Als auch noch Kanada die Aufnahme verweigert, ger\u00e4t die Fahrt in die Freiheit zur Odyssee auf dem Atlantik.\u201c<\/em><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"freitag13.juni\">Freitag, 13. Juni<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aus der Reihe \u201eGeheimnisvolle Orte\u201c sendet <strong>tagesschau 24<\/strong> um 22.20 Uhr den Beitrag <a href=\"https:\/\/www.ardmediathek.de\/video\/geheimnisvolle-orte\/das-verlorene-alt-berlin\/rbb\/Y3JpZDovL3JiYl85NGY3OTEwMi1lODE3LTQ4YTYtYTUwZS03YWFiMWNkYWQzMGVfcHVibGljYXRpb24\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eDas verlorene Alt-Berlin\u201c<\/a>. <em>\u201eDie deutsche Hauptstadt hatte einst einen lebendigen Kern, der zwischen Alexanderplatz, Stadtschloss und Spittelmarkt lag: Alt-Berlin. In dieser Dokumentation wird die Geschichte des Verschwindens dieses historischen Kerns erz\u00e4hlt \u2013 von der mittelalterlichen Stadt mit ihren engen Gassen und Fachwerkh\u00e4usern bis hin zur modernen, oft unkenntlichen Metropole.\u201c<\/em><\/li>\n<\/ul>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Viel Spa\u00df bei der Auswahl der Geschichtssendungen! Samstag, 7. Juni Sonntag, 8. Juni \u2013 Pfingsten Montag, 9. Juni \u2013 Pfingstmontag Dienstag, 10. Juni Mittwoch, 11. Juni Heute eine Fehlanzeige. Donnerstag, 12. Juni Freitag, 13. Juni<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[115,126,128,129,123,125],"class_list":["post-5416","post","type-post","status-publish","format-standard","hentry","category-geschichte-im-fernsehen","category-history-tv","tag-archaologie","tag-dokumentation","tag-fernsehen","tag-geschichte","tag-geschichtsfernsehen","tag-spielfilm"],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/posts\/5416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/comments?post=5416"}],"version-history":[{"count":2,"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/posts\/5416\/revisions"}],"predecessor-version":[{"id":5418,"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/posts\/5416\/revisions\/5418"}],"wp:attachment":[{"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/media?parent=5416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/categories?post=5416"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/historikerkraus.de\/blog\/wp-json\/wp\/v2\/tags?post=5416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}